{"id":47024,"date":"2024-09-06T16:36:46","date_gmt":"2024-09-06T23:36:46","guid":{"rendered":"https:\/\/www.nlacrc.org\/?post_type=tribe_events&#038;p=47024"},"modified":"2024-09-06T16:36:46","modified_gmt":"2024-09-06T23:36:46","slug":"fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc","status":"publish","type":"tribe_events","link":"https:\/\/nlacrc.org\/es\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/","title":{"rendered":"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC)"},"content":{"rendered":"<p>Este entrenamiento mensual ayudar\u00e1 a aprender informaci\u00f3n b\u00e1sica acerca del IEP, al igual que estrategias m\u00e1s avanzadas sobre los pasos que puede tomar cuando est\u00e1 en desacuerdo con su IEP.  \u00a1Los padres participantes recibir\u00e1n una copia digital GRATUITA para ayudarlo a crear su portafolio del IEP en casa!<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n, comun\u00edquese con F\u00e1tima\u00a0<a href=\"mailto:maria.castaneda@csun.edu\" target=\"_blank\" rel=\"noopener\">maria.castaneda@csun.edu<\/a><\/p>\n<p>Para registrarse por favor visita:\u00a0<a id=\"ow2424\" href=\"https:\/\/www.google.com\/url?q=https:\/\/csun.zoom.us\/meeting\/register\/tZwkc-uhrD0uG9JADGqSqPDBkx9uo_j3ISVR&amp;sa=D&amp;source=calendar&amp;usd=2&amp;usg=AOvVaw0Rh_7qFd_Nq6RTTlLIModL\" target=\"_blank\" rel=\"noopener\">https:\/\/csun.zoom.us\/meeting\/register\/tZwkc-uhrD0uG9JADGqSqPDBkx9uo_j3ISVR<\/a><\/p>","protected":false},"excerpt":{"rendered":"Este entrenamiento mensual ayudar\u00e1 a aprender informaci\u00f3n b\u00e1sica acerca del IEP, al igual que estrategias m\u00e1s avanzadas sobre los pasos [\u2026]","protected":false},"author":61,"featured_media":47013,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_EventAllDay":false,"_EventTimezone":"America\/Los_Angeles","_EventStartDate":"2024-09-17 12:00:00","_EventEndDate":"2024-09-17 13:00:00","_EventStartDateUTC":"2024-09-17 19:00:00","_EventEndDateUTC":"2024-09-17 20:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"$","_EventCurrencyCode":"USD","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[587],"class_list":["post-47024","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-community","cat_community"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - North Los Angeles County<\/title>\n<meta name=\"description\" content=\"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - Esta entrenamiento mensual ayudar\u00e1 a aprender informaci\u00f3n b\u00e1sica acerca del IEP, al igual que estrategias m\u00e1s avanzadas sobre los pasos que puede tomar\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - North Los Angeles County\" \/>\n<meta property=\"og:description\" content=\"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - Esta entrenamiento mensual ayudar\u00e1 a aprender informaci\u00f3n b\u00e1sica acerca del IEP, al igual que estrategias m\u00e1s avanzadas sobre los pasos que puede tomar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/\" \/>\n<meta property=\"og:site_name\" content=\"North Los Angeles County\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NLACRC\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/live-nlacrc.pantheonsite.io\/wp-content\/uploads\/2024\/09\/fundamentos-del-iep.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NLACRC\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/\",\"url\":\"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/\",\"name\":\"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - North Los Angeles County\",\"isPartOf\":{\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/fundamentos-del-iep.png\",\"datePublished\":\"2024-09-06T23:36:46+00:00\",\"description\":\"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - Esta entrenamiento mensual ayudar\u00e1 a aprender informaci\u00f3n b\u00e1sica acerca del IEP, al igual que estrategias m\u00e1s avanzadas sobre los pasos que puede tomar\",\"breadcrumb\":{\"@id\":\"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/#primaryimage\",\"url\":\"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/fundamentos-del-iep.png\",\"contentUrl\":\"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/fundamentos-del-iep.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.nlacrc.org\/fa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/www.nlacrc.org\/fa\/%d8%aa%d9%82%d9%88%db%8c%d9%85\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#website\",\"url\":\"https:\/\/www.nlacrc.org\/fa\/\",\"name\":\"North Los Angeles County\",\"description\":\"Regional Center\",\"publisher\":{\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nlacrc.org\/fa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#organization\",\"name\":\"North Los Angeles County\",\"url\":\"https:\/\/www.nlacrc.org\/fa\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.nlacrc.org\/wp-content\/uploads\/2024\/06\/logo.svg\",\"contentUrl\":\"https:\/\/www.nlacrc.org\/wp-content\/uploads\/2024\/06\/logo.svg\",\"width\":131,\"height\":130,\"caption\":\"North Los Angeles County\"},\"image\":{\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/NLACRC\/\",\"https:\/\/x.com\/NLACRC\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - North Los Angeles County","description":"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - Este entrenamiento mensual ayudar\u00e1 a aprender informaci\u00f3n b\u00e1sica acerca del IEP, al igual que estrategias m\u00e1s avanzadas sobre los pasos que puede tomar","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_MX","og_type":"article","og_title":"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - North Los Angeles County","og_description":"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - Esta entrenamiento mensual ayudar\u00e1 a aprender informaci\u00f3n b\u00e1sica acerca del IEP, al igual que estrategias m\u00e1s avanzadas sobre los pasos que puede tomar","og_url":"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/","og_site_name":"North Los Angeles County","article_publisher":"https:\/\/www.facebook.com\/NLACRC\/","og_image":[{"width":1080,"height":1080,"url":"https:\/\/live-nlacrc.pantheonsite.io\/wp-content\/uploads\/2024\/09\/fundamentos-del-iep.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@NLACRC","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/","url":"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/","name":"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - North Los Angeles County","isPartOf":{"@id":"https:\/\/www.nlacrc.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/#primaryimage"},"image":{"@id":"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/#primaryimage"},"thumbnailUrl":"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/fundamentos-del-iep.png","datePublished":"2024-09-06T23:36:46+00:00","description":"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC) - Este entrenamiento mensual ayudar\u00e1 a aprender informaci\u00f3n b\u00e1sica acerca del IEP, al igual que estrategias m\u00e1s avanzadas sobre los pasos que puede tomar","breadcrumb":{"@id":"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/#primaryimage","url":"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/fundamentos-del-iep.png","contentUrl":"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/fundamentos-del-iep.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/live-nlacrc.pantheonsite.io\/fa\/calendar\/fundamentos-del-iep-preparando-y-empoderando-a-los-padres-para-el-iep-de-sus-hijos-ffrc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nlacrc.org\/fa\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.nlacrc.org\/fa\/%d8%aa%d9%82%d9%88%db%8c%d9%85\/"},{"@type":"ListItem","position":3,"name":"Fundamentos del IEP: Preparando y Empoderando a los Padres para el IEP de sus Hijos (FFRC)"}]},{"@type":"WebSite","@id":"https:\/\/www.nlacrc.org\/fa\/#website","url":"https:\/\/www.nlacrc.org\/fa\/","name":"Norte del condado de Los \u00c1ngeles","description":"Centro Regional","publisher":{"@id":"https:\/\/www.nlacrc.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nlacrc.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.nlacrc.org\/fa\/#organization","name":"Norte del condado de Los \u00c1ngeles","url":"https:\/\/www.nlacrc.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nlacrc.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/www.nlacrc.org\/wp-content\/uploads\/2024\/06\/logo.svg","contentUrl":"https:\/\/www.nlacrc.org\/wp-content\/uploads\/2024\/06\/logo.svg","width":131,"height":130,"caption":"North Los Angeles County"},"image":{"@id":"https:\/\/www.nlacrc.org\/fa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NLACRC\/","https:\/\/x.com\/NLACRC"]}]}},"featured_img":"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/fundamentos-del-iep.png","coauthors":[],"author_meta":{"author_link":"https:\/\/nlacrc.org\/es\/author\/jvanderiet\/","display_name":"jvanderiet"},"relative_dates":{"created":"Publicado 2 a\u00f1os hace","modified":"Actualizado 2 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el septiembre 6, 2024","modified":"Actualizado el septiembre 6, 2024"},"absolute_dates_time":{"created":"Publicado el septiembre 6, 2024 4:36 pm","modified":"Actualizado el septiembre 6, 2024 4:36 pm"},"featured_img_caption":"","tax_additional":{"post_tag":{"linked":[],"unlinked":[],"slug":"post_tag","name":"Etiquetas"},"tribe_events_cat":{"linked":["<a href=\"https:\/\/nlacrc.org\/es\/calendar\/categoria\/events\/community\/\" class=\"advgb-post-tax-term\">Community<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Community<\/span>"],"slug":"tribe_events_cat","name":"Categor\u00edas de Evento"}},"series_order":"","_links":{"self":[{"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tribe_events\/47024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/users\/61"}],"version-history":[{"count":2,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tribe_events\/47024\/revisions"}],"predecessor-version":[{"id":47026,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tribe_events\/47024\/revisions\/47026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/media\/47013"}],"wp:attachment":[{"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/media?parent=47024"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tags?post=47024"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=47024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}