{"id":47004,"date":"2024-09-06T16:35:26","date_gmt":"2024-09-06T23:35:26","guid":{"rendered":"https:\/\/www.nlacrc.org\/?post_type=tribe_events&#038;p=47004"},"modified":"2024-09-06T16:35:26","modified_gmt":"2024-09-06T23:35:26","slug":"el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc","status":"publish","type":"tribe_events","link":"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/","title":{"rendered":"El Poder del Amor y la Paciencia-Grupo de Apoyo Presencial (FFRC)"},"content":{"rendered":"<p>Grupo de Apoyo para Padres con Hijos de Necesidades Especiales (espa\u00f1ol)<\/p>\n<p>Las reuniones son presenciales el segundo viernes de cada mes de 9:30 am a 11:00 am.<br \/>\nDirecci\u00f3n: Centro de Recursos Comunitarios LA Care 7868 Van Nuys Blvd. Panorama City, CA 91402<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n env\u00ede un correo electr\u00f3nico o llame al (818) 677-6854 o\u00a0<a href=\"mailto:rebeca.diaz@csun.edu\" target=\"_blank\" rel=\"noopener\">rebeca.diaz@csun.edu<\/a><\/p>\n<p><strong>Las reuniones en persona fueron el 9 de agosto, 13 de septiembre, 11 de octubre, 8 de noviembre y 13 de diciembre.\u00a0<\/strong><\/p>","protected":false},"excerpt":{"rendered":"Grupo de Apoyo para Padres con Hijos de Necesidades Especiales (espa\u00f1ol) Las reuniones son presenciales el segundo viernes de cada [\u2026]","protected":false},"author":61,"featured_media":47007,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_EventAllDay":false,"_EventTimezone":"America\/Los_Angeles","_EventStartDate":"2024-09-13 09:30:00","_EventEndDate":"2024-09-13 11:00:00","_EventStartDateUTC":"2024-09-13 16:30:00","_EventEndDateUTC":"2024-09-13 18:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"$","_EventCurrencyCode":"USD","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[587],"class_list":["post-47004","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-community","cat_community"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - North Los Angeles County<\/title>\n<meta name=\"description\" content=\"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - Grupo de Apoyo para Padres con Hijos de Necesidades Especiales (espa\u00f1ol) Las reuniones son presenciales el segundo viernes de cada mes de 9:30 am a\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - North Los Angeles County\" \/>\n<meta property=\"og:description\" content=\"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - Grupo de Apoyo para Padres con Hijos de Necesidades Especiales (espa\u00f1ol) Las reuniones son presenciales el segundo viernes de cada mes de 9:30 am a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/\" \/>\n<meta property=\"og:site_name\" content=\"North Los Angeles County\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NLACRC\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/2024-el-poder-del-amor-y-la-paciencia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NLACRC\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/\",\"url\":\"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/\",\"name\":\"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - North Los Angeles County\",\"isPartOf\":{\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/2024-el-poder-del-amor-y-la-paciencia.jpg\",\"datePublished\":\"2024-09-06T23:35:26+00:00\",\"description\":\"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - Grupo de Apoyo para Padres con Hijos de Necesidades Especiales (espa\u00f1ol) Las reuniones son presenciales el segundo viernes de cada mes de 9:30 am a\",\"breadcrumb\":{\"@id\":\"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/#primaryimage\",\"url\":\"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/2024-el-poder-del-amor-y-la-paciencia.jpg\",\"contentUrl\":\"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/2024-el-poder-del-amor-y-la-paciencia.jpg\",\"width\":840,\"height\":840},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.nlacrc.org\/fa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/www.nlacrc.org\/fa\/%d8%aa%d9%82%d9%88%db%8c%d9%85\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#website\",\"url\":\"https:\/\/www.nlacrc.org\/fa\/\",\"name\":\"North Los Angeles County\",\"description\":\"Regional Center\",\"publisher\":{\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nlacrc.org\/fa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#organization\",\"name\":\"North Los Angeles County\",\"url\":\"https:\/\/www.nlacrc.org\/fa\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.nlacrc.org\/wp-content\/uploads\/2024\/06\/logo.svg\",\"contentUrl\":\"https:\/\/www.nlacrc.org\/wp-content\/uploads\/2024\/06\/logo.svg\",\"width\":131,\"height\":130,\"caption\":\"North Los Angeles County\"},\"image\":{\"@id\":\"https:\/\/www.nlacrc.org\/fa\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/NLACRC\/\",\"https:\/\/x.com\/NLACRC\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - North Los Angeles County","description":"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - Grupo de Apoyo para Padres con Hijos de Necesidades Especiales (espa\u00f1ol) Las reuniones son presenciales el segundo viernes de cada mes de 9:30 am a","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_MX","og_type":"article","og_title":"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - North Los Angeles County","og_description":"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - Grupo de Apoyo para Padres con Hijos de Necesidades Especiales (espa\u00f1ol) Las reuniones son presenciales el segundo viernes de cada mes de 9:30 am a","og_url":"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/","og_site_name":"North Los Angeles County","article_publisher":"https:\/\/www.facebook.com\/NLACRC\/","og_image":[{"width":840,"height":840,"url":"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/2024-el-poder-del-amor-y-la-paciencia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@NLACRC","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/","url":"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/","name":"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - North Los Angeles County","isPartOf":{"@id":"https:\/\/www.nlacrc.org\/fa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/#primaryimage"},"image":{"@id":"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/#primaryimage"},"thumbnailUrl":"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/2024-el-poder-del-amor-y-la-paciencia.jpg","datePublished":"2024-09-06T23:35:26+00:00","description":"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC) - Grupo de Apoyo para Padres con Hijos de Necesidades Especiales (espa\u00f1ol) Las reuniones son presenciales el segundo viernes de cada mes de 9:30 am a","breadcrumb":{"@id":"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/#primaryimage","url":"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/2024-el-poder-del-amor-y-la-paciencia.jpg","contentUrl":"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/2024-el-poder-del-amor-y-la-paciencia.jpg","width":840,"height":840},{"@type":"BreadcrumbList","@id":"https:\/\/nlacrc.org\/es\/calendar\/el-poder-del-amor-y-la-paciencia-support-group-in-person-ffrc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nlacrc.org\/fa\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.nlacrc.org\/fa\/%d8%aa%d9%82%d9%88%db%8c%d9%85\/"},{"@type":"ListItem","position":3,"name":"El Poder del Amor y la Paciencia-Support Group In-Person (FFRC)"}]},{"@type":"WebSite","@id":"https:\/\/www.nlacrc.org\/fa\/#website","url":"https:\/\/www.nlacrc.org\/fa\/","name":"Norte del condado de Los \u00c1ngeles","description":"Centro Regional","publisher":{"@id":"https:\/\/www.nlacrc.org\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nlacrc.org\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.nlacrc.org\/fa\/#organization","name":"Norte del condado de Los \u00c1ngeles","url":"https:\/\/www.nlacrc.org\/fa\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nlacrc.org\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/www.nlacrc.org\/wp-content\/uploads\/2024\/06\/logo.svg","contentUrl":"https:\/\/www.nlacrc.org\/wp-content\/uploads\/2024\/06\/logo.svg","width":131,"height":130,"caption":"North Los Angeles County"},"image":{"@id":"https:\/\/www.nlacrc.org\/fa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NLACRC\/","https:\/\/x.com\/NLACRC"]}]}},"featured_img":"https:\/\/nlacrc.org\/wp-content\/uploads\/2024\/09\/2024-el-poder-del-amor-y-la-paciencia.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/nlacrc.org\/es\/author\/jvanderiet\/","display_name":"jvanderiet"},"relative_dates":{"created":"Publicado 2 a\u00f1os hace","modified":"Actualizado 2 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el septiembre 6, 2024","modified":"Actualizado el septiembre 6, 2024"},"absolute_dates_time":{"created":"Publicado el septiembre 6, 2024 4:35 pm","modified":"Actualizado el septiembre 6, 2024 4:35 pm"},"featured_img_caption":"","tax_additional":{"post_tag":{"linked":[],"unlinked":[],"slug":"post_tag","name":"Etiquetas"},"tribe_events_cat":{"linked":["<a href=\"https:\/\/nlacrc.org\/es\/calendar\/categoria\/events\/community\/\" class=\"advgb-post-tax-term\">Community<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Community<\/span>"],"slug":"tribe_events_cat","name":"Categor\u00edas de Evento"}},"series_order":"","_links":{"self":[{"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tribe_events\/47004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/users\/61"}],"version-history":[{"count":2,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tribe_events\/47004\/revisions"}],"predecessor-version":[{"id":47019,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tribe_events\/47004\/revisions\/47019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/media\/47007"}],"wp:attachment":[{"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/media?parent=47004"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tags?post=47004"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/nlacrc.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=47004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}